{"id":17,"date":"2015-07-13T16:22:43","date_gmt":"2015-07-13T16:22:43","guid":{"rendered":"http:\/\/ifbarcelona.cat\/?page_id=17"},"modified":"2015-11-02T13:49:26","modified_gmt":"2015-11-02T13:49:26","slug":"sala-de-premsa","status":"publish","type":"page","link":"https:\/\/ifbarcelona.cat\/es\/sala-de-premsa\/","title":{"rendered":"Sala de prensa"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":16,"comment_status":"open","ping_status":"open","template":"saladepremsa.php","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-17","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sala de prensa &#8211; IF Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ifbarcelona.cat\/es\/sala-de-premsa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sala de prensa &#8211; IF Barcelona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ifbarcelona.cat\/es\/sala-de-premsa\/\" \/>\n<meta property=\"og:site_name\" content=\"IF Barcelona\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-02T13:49:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ifbarcelona.cat\/wp-content\/uploads\/2015\/07\/if2019_home_WEB_v3.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ifbarcelona.cat\\\/es\\\/sala-de-premsa\\\/\",\"url\":\"https:\\\/\\\/ifbarcelona.cat\\\/es\\\/sala-de-premsa\\\/\",\"name\":\"Sala de prensa &#8211; IF Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ifbarcelona.cat\\\/es\\\/#website\"},\"datePublished\":\"2015-07-13T16:22:43+00:00\",\"dateModified\":\"2015-11-02T13:49:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ifbarcelona.cat\\\/es\\\/sala-de-premsa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/ifbarcelona.cat\\\/es\\\/sala-de-premsa\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ifbarcelona.cat\\\/es\\\/sala-de-premsa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/ifbarcelona.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sala de premsa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ifbarcelona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ifbarcelona.cat\\\/es\\\/\",\"name\":\"IF Barcelona\",\"description\":\"La mirada o el plaer de mirar (dramat\u00f9rgies de la imatge)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ifbarcelona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sala de prensa &#8211; IF Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ifbarcelona.cat\/es\/sala-de-premsa\/","og_locale":"es_ES","og_type":"article","og_title":"Sala de prensa &#8211; IF Barcelona","og_url":"https:\/\/ifbarcelona.cat\/es\/sala-de-premsa\/","og_site_name":"IF Barcelona","article_modified_time":"2015-11-02T13:49:26+00:00","og_image":[{"url":"http:\/\/ifbarcelona.cat\/wp-content\/uploads\/2015\/07\/if2019_home_WEB_v3.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ifbarcelona.cat\/es\/sala-de-premsa\/","url":"https:\/\/ifbarcelona.cat\/es\/sala-de-premsa\/","name":"Sala de prensa &#8211; IF Barcelona","isPartOf":{"@id":"https:\/\/ifbarcelona.cat\/es\/#website"},"datePublished":"2015-07-13T16:22:43+00:00","dateModified":"2015-11-02T13:49:26+00:00","breadcrumb":{"@id":"https:\/\/ifbarcelona.cat\/es\/sala-de-premsa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/ifbarcelona.cat\/es\/sala-de-premsa\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ifbarcelona.cat\/es\/sala-de-premsa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/ifbarcelona.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Sala de premsa"}]},{"@type":"WebSite","@id":"https:\/\/ifbarcelona.cat\/es\/#website","url":"https:\/\/ifbarcelona.cat\/es\/","name":"IF Barcelona","description":"La mirada o el plaer de mirar (dramat\u00f9rgies de la imatge)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ifbarcelona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/ifbarcelona.cat\/es\/wp-json\/wp\/v2\/pages\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ifbarcelona.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ifbarcelona.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ifbarcelona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ifbarcelona.cat\/es\/wp-json\/wp\/v2\/comments?post=17"}],"version-history":[{"count":3,"href":"https:\/\/ifbarcelona.cat\/es\/wp-json\/wp\/v2\/pages\/17\/revisions"}],"predecessor-version":[{"id":789,"href":"https:\/\/ifbarcelona.cat\/es\/wp-json\/wp\/v2\/pages\/17\/revisions\/789"}],"wp:attachment":[{"href":"https:\/\/ifbarcelona.cat\/es\/wp-json\/wp\/v2\/media?parent=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}